{"id":3842,"date":"2023-02-27T14:52:17","date_gmt":"2023-02-27T14:52:17","guid":{"rendered":"https:\/\/xdsomename.tempurl.host\/ukiyo-website\/product\/palos-de-fragancia-de-lujo-blanco\/"},"modified":"2026-08-11T01:14:30","modified_gmt":"2026-08-11T01:14:30","slug":"palos-de-fragancia-de-lujo-blanco","status":"publish","type":"product","link":"https:\/\/ukiyo-home.com\/es\/palos-de-fragancia-de-lujo-blanco\/","title":{"rendered":"Palos de fragancia de lujo, blanco"},"content":{"rendered":"<p>Dale a cada espacio su propia personalidad con este hermoso set de incienso de lujo Ukiyo. Ukiyo significa vivir el momento, disfrutar y apreciar cada momento precioso! Los palos de fragancia dan un maravilloso aroma sutil. Presentado en caja de regalo. Capacidad 50ml.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dale a cada espacio su propia personalidad con este hermoso set de incienso de lujo Ukiyo. Ukiyo significa vivir el momento, disfrutar y apreciar cada momento precioso! Los palos de fragancia dan un maravilloso aroma sutil. Presentado en caja de regalo. Capacidad 50ml.<\/p>\n","protected":false},"featured_media":14458,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[57],"product_tag":[],"class_list":["post-3842","product","type-product","status-publish","has-post-thumbnail","product_cat-decoracion-es","pa_color-white","first","instock","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Palos de fragancia de lujo, blanco - Ukiyo Home<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ukiyo-home.com\/es\/palos-de-fragancia-de-lujo-blanco\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Palos de fragancia de lujo, blanco - Ukiyo Home\" \/>\n<meta property=\"og:description\" content=\"Dale a cada espacio su propia personalidad con este hermoso set de incienso de lujo Ukiyo. Ukiyo significa vivir el momento, disfrutar y apreciar cada momento precioso! Los palos de fragancia dan un maravilloso aroma sutil. Presentado en caja de regalo. Capacidad 50ml.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ukiyo-home.com\/es\/palos-de-fragancia-de-lujo-blanco\/\" \/>\n<meta property=\"og:site_name\" content=\"Ukiyo Home\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-11T01:14:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ukiyo-home.com\/wp-content\/uploads\/sites\/7\/2026\/04\/P262.953__S_0__201837d074d1476fbb784ab2a0dee043.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ukiyo-home.com\\\/es\\\/palos-de-fragancia-de-lujo-blanco\\\/\",\"url\":\"https:\\\/\\\/ukiyo-home.com\\\/es\\\/palos-de-fragancia-de-lujo-blanco\\\/\",\"name\":\"Palos de fragancia de lujo, blanco - Ukiyo Home\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ukiyo-home.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ukiyo-home.com\\\/es\\\/palos-de-fragancia-de-lujo-blanco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ukiyo-home.com\\\/es\\\/palos-de-fragancia-de-lujo-blanco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ukiyo-home.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/04\\\/P262.953__S_0__201837d074d1476fbb784ab2a0dee043.jpg\",\"datePublished\":\"2023-02-27T14:52:17+00:00\",\"dateModified\":\"2026-08-11T01:14:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ukiyo-home.com\\\/es\\\/palos-de-fragancia-de-lujo-blanco\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ukiyo-home.com\\\/es\\\/palos-de-fragancia-de-lujo-blanco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ukiyo-home.com\\\/es\\\/palos-de-fragancia-de-lujo-blanco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ukiyo-home.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/04\\\/P262.953__S_0__201837d074d1476fbb784ab2a0dee043.jpg\",\"contentUrl\":\"https:\\\/\\\/ukiyo-home.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/04\\\/P262.953__S_0__201837d074d1476fbb784ab2a0dee043.jpg\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ukiyo-home.com\\\/es\\\/palos-de-fragancia-de-lujo-blanco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ukiyo-home.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Colecci\u00f3n\",\"item\":\"https:\\\/\\\/ukiyo-home.com\\\/es\\\/coleccion-es\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Palos de fragancia de lujo, blanco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ukiyo-home.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ukiyo-home.com\\\/es\\\/\",\"name\":\"Ukiyo Home\",\"description\":\"Just another Swiss Peak Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ukiyo-home.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Palos de fragancia de lujo, blanco - Ukiyo Home","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ukiyo-home.com\/es\/palos-de-fragancia-de-lujo-blanco\/","og_locale":"es_ES","og_type":"article","og_title":"Palos de fragancia de lujo, blanco - Ukiyo Home","og_description":"Dale a cada espacio su propia personalidad con este hermoso set de incienso de lujo Ukiyo. Ukiyo significa vivir el momento, disfrutar y apreciar cada momento precioso! Los palos de fragancia dan un maravilloso aroma sutil. Presentado en caja de regalo. Capacidad 50ml.","og_url":"https:\/\/ukiyo-home.com\/es\/palos-de-fragancia-de-lujo-blanco\/","og_site_name":"Ukiyo Home","article_modified_time":"2026-08-11T01:14:30+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/ukiyo-home.com\/wp-content\/uploads\/sites\/7\/2026\/04\/P262.953__S_0__201837d074d1476fbb784ab2a0dee043.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ukiyo-home.com\/es\/palos-de-fragancia-de-lujo-blanco\/","url":"https:\/\/ukiyo-home.com\/es\/palos-de-fragancia-de-lujo-blanco\/","name":"Palos de fragancia de lujo, blanco - Ukiyo Home","isPartOf":{"@id":"https:\/\/ukiyo-home.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ukiyo-home.com\/es\/palos-de-fragancia-de-lujo-blanco\/#primaryimage"},"image":{"@id":"https:\/\/ukiyo-home.com\/es\/palos-de-fragancia-de-lujo-blanco\/#primaryimage"},"thumbnailUrl":"https:\/\/ukiyo-home.com\/wp-content\/uploads\/sites\/7\/2026\/04\/P262.953__S_0__201837d074d1476fbb784ab2a0dee043.jpg","datePublished":"2023-02-27T14:52:17+00:00","dateModified":"2026-08-11T01:14:30+00:00","breadcrumb":{"@id":"https:\/\/ukiyo-home.com\/es\/palos-de-fragancia-de-lujo-blanco\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ukiyo-home.com\/es\/palos-de-fragancia-de-lujo-blanco\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ukiyo-home.com\/es\/palos-de-fragancia-de-lujo-blanco\/#primaryimage","url":"https:\/\/ukiyo-home.com\/wp-content\/uploads\/sites\/7\/2026\/04\/P262.953__S_0__201837d074d1476fbb784ab2a0dee043.jpg","contentUrl":"https:\/\/ukiyo-home.com\/wp-content\/uploads\/sites\/7\/2026\/04\/P262.953__S_0__201837d074d1476fbb784ab2a0dee043.jpg","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/ukiyo-home.com\/es\/palos-de-fragancia-de-lujo-blanco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ukiyo-home.com\/es\/"},{"@type":"ListItem","position":2,"name":"Colecci\u00f3n","item":"https:\/\/ukiyo-home.com\/es\/coleccion-es\/"},{"@type":"ListItem","position":3,"name":"Palos de fragancia de lujo, blanco"}]},{"@type":"WebSite","@id":"https:\/\/ukiyo-home.com\/es\/#website","url":"https:\/\/ukiyo-home.com\/es\/","name":"Ukiyo Home","description":"Just another Swiss Peak Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ukiyo-home.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/ukiyo-home.com\/es\/wp-json\/wp\/v2\/product\/3842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ukiyo-home.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ukiyo-home.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ukiyo-home.com\/es\/wp-json\/wp\/v2\/comments?post=3842"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ukiyo-home.com\/es\/wp-json\/wp\/v2\/media\/14458"}],"wp:attachment":[{"href":"https:\/\/ukiyo-home.com\/es\/wp-json\/wp\/v2\/media?parent=3842"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ukiyo-home.com\/es\/wp-json\/wp\/v2\/product_brand?post=3842"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ukiyo-home.com\/es\/wp-json\/wp\/v2\/product_cat?post=3842"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ukiyo-home.com\/es\/wp-json\/wp\/v2\/product_tag?post=3842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}